{"id":1446,"date":"2015-07-22T16:30:07","date_gmt":"2015-07-22T14:30:07","guid":{"rendered":"http:\/\/www.audiosatpro.es\/?p=1446"},"modified":"2015-07-22T18:39:44","modified_gmt":"2015-07-22T16:39:44","slug":"bss-presenta-nueva-plataforma-soundweb-contrio","status":"publish","type":"post","link":"https:\/\/www.audiosatpro.es\/index.php\/bss-presenta-nueva-plataforma-soundweb-contrio\/","title":{"rendered":"BSS presenta su nueva plataforma Soundweb Contrio"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0 BSS ha presentado recientemente la nueva plataforma de distribuci\u00f3n de audio y control en red, Soundweb Contrio y sus dos productos iniciales (el Contrio Server y una gama de controladores de pared). \u00c9stos son los primeros miembros de la familia Contrio\u00a0y proporcionan una capacidad mejorada para controlar sistemas, \u00a0as\u00ed como mayor flexibilidad de enrutamiento de audio para una amplia variedad de aplicaciones.<span id=\"more-5211\"><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contrioserver.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1463\" src=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contrioserver.jpg\" alt=\"BSS Contrio Server\" width=\"800\" height=\"75\" srcset=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contrioserver.jpg 1000w, https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contrioserver-300x28.jpg 300w, https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contrioserver-900x85.jpg 900w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contriopanel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1464\" src=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contriopanel-300x295.jpg\" alt=\"BSS Contrio Panel\" width=\"300\" height=\"295\" srcset=\"https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contriopanel-300x295.jpg 300w, https:\/\/www.audiosatpro.es\/wp-content\/uploads\/contriopanel.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00a0 El Soundweb Contrio Server es un m\u00f3dulo que ocupa tan s\u00f3lo una unidad de rack y ofrece las siguientes funcionalidades:<\/p>\n<p style=\"text-align: justify;\">\u00a0 <strong>Control avanzado del sistema:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0 El Contrio Server habilita la extensa configuraci\u00f3n l\u00f3gica de control del sistema, tanto con la filosof\u00eda de \u201ccableado\u201d a trav\u00e9s del software Audio Architect (que ya exist\u00eda para los dispositivos Soundweb London), como con un nuevo entorno de programaci\u00f3n llamado Lua. El sistema se hace as\u00ed m\u00e1s eficiente mediante la ejecuci\u00f3n de un sistema l\u00f3gico, \u00a0separado de los dispositivos de audio, liberando capacidad de proceso y reduciendo la cantidad de hardware requerido.<\/p>\n<p style=\"text-align: justify;\">\u00a0 <strong>Gesti\u00f3n del sistema:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0 El Contrio Server incluye una funcionalidad de auto-recuperaci\u00f3n y de gesti\u00f3n de fallos. Mediante la monitorizaci\u00f3n del switch Ethernet y de los puertos a los que est\u00e1n conectados todos los dispositivos, s\u00f3lo necesitaremos reemplazar un dispositivo por otro en el mismo puerto del switch. El Contrio Server cargar\u00e1 a continuaci\u00f3n remota y autom\u00e1ticamente toda la configuraci\u00f3n y direccionamiento del nuevo dispositivo que instalemos, \u00a0para que \u00e9stos se ajusten a los del anterior. De este modo, no es necesario ejecutar una aplicaci\u00f3n software para a\u00f1adir dispositivos de sustituci\u00f3n al sistema.<\/p>\n<p style=\"text-align: justify;\">\u00a0 <strong>Servidor:<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0 El Contrio Server ofrece la funcionalidad de almacenar mensajes de audio y llamadas a presets, \u00a0as\u00ed como su programaci\u00f3n. Esto permite reproducir dichos mensajes y ejecutar las llamadas a presets en la red de dispositivos, de acuerdo a los programas establecidos.<\/p>\n<p style=\"text-align: justify;\">\u00a0 Este servidor es compatible con los protocolos HARMAN BLU y Dante, de modo que se puede integrar en una amplia variedad de configuraciones.<\/p>\n<p style=\"text-align: justify;\">\u00a0 El Soundweb Contrio Server ejecuta una versi\u00f3n embebida de HiQnet Audio Architect y es, \u00a0por tanto, \u00a0capaz, \u00a0de ofrecer inmediatamente a los integradores y a usuarios finales una gesti\u00f3n extensa de todos los presets del sistema, backups, almacenamiento de modos de ajuste de localizaciones espec\u00edficas y agregaci\u00f3n y programaci\u00f3n de eventos.<\/p>\n<p style=\"text-align: justify;\">\u00a0 Por su parte, la l\u00ednea Contrio de controladores de pared cuenta con seis modelos. Cuatro de ellos se conectan al Media Server v\u00eda Ethernet y, adem\u00e1s de incluir control avanzado de m\u00faltiples zonas, se pueden usar f\u00e1cilmente en un entorno de uni\u00f3n y divisi\u00f3n de salas. Los dos restantes son controladores anal\u00f3gicos sencillos, para conectar a las entradas de prop\u00f3sito general (GPI) y controlar con ellos el par\u00e1metro que deseemos (que frecuentemente ser\u00e1 el volumen o la selecci\u00f3n de fuentes o presets). Todos estos controladores est\u00e1n disponibles en blanco y negro y con formatos europeos y americanos. Todos ellos muestran informaci\u00f3n visual a los usuarios para que puedan gestionar y ajustar m\u00e1s f\u00e1cilmente el funcionamiento del audio, \u00a0en un entorno espec\u00edfico.<\/p>\n<p style=\"text-align: justify;\">\u00a0 Estos equipos Soundweb Contrio, as\u00ed como los que se desarrollar\u00e1n en el futuro, son compatibles con los dispositivos Soundweb London de BSS. Esto permite ofrecer la m\u00e1s amplia y completa gama de dispositivos de proceso, distribuci\u00f3n y control de audio, disponible hoy en d\u00eda, aportando una soluci\u00f3n con un \u00fanico sistema.<\/p>\n<p style=\"text-align: justify;\"><i>\u00a0 \u201cDesarrollamos estos productos para permitir a los integradores continuar desplegando la l\u00ednea completa de dispositivos Soundweb London y el Software HiQnet, pero tambi\u00e9n d\u00e1ndoles la capacidad de tener un control mejorado y monitorizaci\u00f3n del sistema a trav\u00e9s de los primeros dispositivos Contrio\u201d<\/i> comenta Iain Gregory, Market Manager, Installed Sound en Harman Signal Processing.<\/p>\n<p style=\"text-align: justify;\">\u00a0 Fuente:\u00a0EARPRO.<\/p>\n<p style=\"text-align: justify;\">\u00a0 M\u00e1s informaci\u00f3n y compra, <a href=\"http:\/\/www.aspstore.es\" target=\"_blank\">ASP Store<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 BSS ha presentado recientemente la nueva plataforma de distribuci\u00f3n de audio y control en red, Soundweb Contrio y sus dos productos iniciales (el Contrio<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[647,16,649,650,648,646],"class_list":["post-1446","post","type-post","status-publish","format-standard","hentry","category-sonidoprofesional","tag-audio-architect","tag-bss","tag-contrio-matrices","tag-dante","tag-london-architect","tag-soundweb"],"_links":{"self":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/posts\/1446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/comments?post=1446"}],"version-history":[{"count":4,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/posts\/1446\/revisions"}],"predecessor-version":[{"id":1492,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/posts\/1446\/revisions\/1492"}],"wp:attachment":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/media?parent=1446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/categories?post=1446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/tags?post=1446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}