{"id":52,"count":1,"description":"","link":"https:\/\/www.audiosatpro.es\/index.php\/tag\/woofer\/","name":"woofer","slug":"woofer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/tags\/52"}],"collection":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.audiosatpro.es\/index.php\/wp-json\/wp\/v2\/posts?tags=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}